{"id":640,"count":1,"description":"","link":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/tag\/california-wine\/","name":"California wine","slug":"california-wine","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>California wine Archives - CDFA&#039;s Planting Seeds Blog<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/tag\/california-wine\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"California wine Archives - CDFA&#039;s Planting Seeds Blog\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/tag\/california-wine\/\" \/>\r\n<meta property=\"og:site_name\" content=\"CDFA&#039;s Planting Seeds Blog\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/index.php\\\/tag\\\/california-wine\\\/\",\"url\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/index.php\\\/tag\\\/california-wine\\\/\",\"name\":\"California wine Archives - CDFA&#039;s Planting Seeds Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/index.php\\\/tag\\\/california-wine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/index.php\\\/tag\\\/california-wine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"California wine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/#website\",\"url\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/\",\"name\":\"CDFA's Planting Seeds Blog\",\"description\":\"Making California a better place to live because of what we grow and how we grow it.\",\"publisher\":{\"@id\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/#organization\",\"name\":\"CDFA's Planting Seeds Blog\",\"url\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/wordpress\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/CDFA-logo-horizontal-hi-res-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/wordpress\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/CDFA-logo-horizontal-hi-res-scaled.jpg\",\"width\":2560,\"height\":585,\"caption\":\"CDFA's Planting Seeds Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/plantingseedsblog.cdfa.ca.gov\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"California wine Archives - CDFA&#039;s Planting Seeds Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/tag\/california-wine\/","og_locale":"en_US","og_type":"article","og_title":"California wine Archives - CDFA&#039;s Planting Seeds Blog","og_url":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/tag\/california-wine\/","og_site_name":"CDFA&#039;s Planting Seeds Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/tag\/california-wine\/","url":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/tag\/california-wine\/","name":"California wine Archives - CDFA&#039;s Planting Seeds Blog","isPartOf":{"@id":"https:\/\/plantingseedsblog.cdfa.ca.gov\/#website"},"breadcrumb":{"@id":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/tag\/california-wine\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/tag\/california-wine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/plantingseedsblog.cdfa.ca.gov\/"},{"@type":"ListItem","position":2,"name":"California wine"}]},{"@type":"WebSite","@id":"https:\/\/plantingseedsblog.cdfa.ca.gov\/#website","url":"https:\/\/plantingseedsblog.cdfa.ca.gov\/","name":"CDFA's Planting Seeds Blog","description":"Making California a better place to live because of what we grow and how we grow it.","publisher":{"@id":"https:\/\/plantingseedsblog.cdfa.ca.gov\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plantingseedsblog.cdfa.ca.gov\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/plantingseedsblog.cdfa.ca.gov\/#organization","name":"CDFA's Planting Seeds Blog","url":"https:\/\/plantingseedsblog.cdfa.ca.gov\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/plantingseedsblog.cdfa.ca.gov\/#\/schema\/logo\/image\/","url":"https:\/\/plantingseedsblog.cdfa.ca.gov\/wordpress\/wp-content\/uploads\/2026\/02\/CDFA-logo-horizontal-hi-res-scaled.jpg","contentUrl":"https:\/\/plantingseedsblog.cdfa.ca.gov\/wordpress\/wp-content\/uploads\/2026\/02\/CDFA-logo-horizontal-hi-res-scaled.jpg","width":2560,"height":585,"caption":"CDFA's Planting Seeds Blog"},"image":{"@id":"https:\/\/plantingseedsblog.cdfa.ca.gov\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/wp-json\/wp\/v2\/tags\/640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/plantingseedsblog.cdfa.ca.gov\/index.php\/wp-json\/wp\/v2\/posts?tags=640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}